{"id":2749,"count":1,"description":"","link":"https:\/\/www.wellsteps.com\/blog\/tag\/government-wellness\/","name":"government wellness","slug":"government-wellness","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>government wellness - Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"government wellness\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wellsteps.com\/blog\/tag\/government-wellness\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wellsteps\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/tag\\\/government-wellness\\\/\",\"url\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/tag\\\/government-wellness\\\/\",\"name\":\"government wellness - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/tag\\\/government-wellness\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/tag\\\/government-wellness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"government wellness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/\",\"name\":\"Blog\",\"description\":\"Effective Employee Wellness Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/#organization\",\"name\":\"WellSteps\",\"url\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logo1.jpg\",\"width\":2443,\"height\":760,\"caption\":\"WellSteps\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wellsteps.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WellSteps\\\/\",\"https:\\\/\\\/x.com\\\/wellsteps\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wellsteps\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWdZuzr-WBwUtgxUr6sC4jQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"government wellness - Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"government wellness","og_url":"https:\/\/www.wellsteps.com\/blog\/tag\/government-wellness\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_site":"@wellsteps","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.wellsteps.com\/blog\/tag\/government-wellness\/","url":"https:\/\/www.wellsteps.com\/blog\/tag\/government-wellness\/","name":"government wellness - Blog","isPartOf":{"@id":"https:\/\/www.wellsteps.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.wellsteps.com\/blog\/tag\/government-wellness\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wellsteps.com\/blog\/tag\/government-wellness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wellsteps.com\/blog\/"},{"@type":"ListItem","position":2,"name":"government wellness"}]},{"@type":"WebSite","@id":"https:\/\/www.wellsteps.com\/blog\/#website","url":"https:\/\/www.wellsteps.com\/blog\/","name":"Blog","description":"Effective Employee Wellness Solutions","publisher":{"@id":"https:\/\/www.wellsteps.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wellsteps.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.wellsteps.com\/blog\/#organization","name":"WellSteps","url":"https:\/\/www.wellsteps.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.wellsteps.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.wellsteps.com\/blog\/wp-content\/uploads\/2015\/12\/logo1.jpg","contentUrl":"https:\/\/www.wellsteps.com\/blog\/wp-content\/uploads\/2015\/12\/logo1.jpg","width":2443,"height":760,"caption":"WellSteps"},"image":{"@id":"https:\/\/www.wellsteps.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WellSteps\/","https:\/\/x.com\/wellsteps","https:\/\/www.linkedin.com\/company\/wellsteps","https:\/\/www.youtube.com\/channel\/UCWdZuzr-WBwUtgxUr6sC4jQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.wellsteps.com\/blog\/wp-json\/wp\/v2\/tags\/2749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wellsteps.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.wellsteps.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.wellsteps.com\/blog\/wp-json\/wp\/v2\/posts?tags=2749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}